{"id":1476,"date":"2024-05-09T14:12:14","date_gmt":"2024-05-09T14:12:14","guid":{"rendered":"https:\/\/just-faster.com\/archive-job-openings\/servicenow-zertifizierter-master-architekt-fortuna\/"},"modified":"2024-06-07T10:44:58","modified_gmt":"2024-06-07T10:44:58","slug":"servicenow-zertifizierter-master-architekt-fortuna","status":"publish","type":"job-openings","link":"https:\/\/just-faster.com\/de\/archive-job-openings\/servicenow-zertifizierter-master-architekt-fortuna\/","title":{"rendered":"ServiceNow Zertifizierter Master Architekt (Fortuna)"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\">Job-Anforderungen:<\/h5>\n\n<ul class=\"wp-block-list\">\n<li>ServiceNow Certified Master Architect Zertifizierung.<\/li>\n\n\n\n<li>Umfassende Erfahrung mit der Implementierung der ServiceNow-Plattform und dem Entwurf der Architektur.<\/li>\n\n\n\n<li>Starke Probleml\u00f6sungs- und analytische F\u00e4higkeiten.<\/li>\n\n\n\n<li>Die F\u00e4higkeit, j\u00fcngere Teammitglieder zu f\u00fchren und zu betreuen.<\/li>\n<\/ul>\n\n<div style=\"height:1rem\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h5 class=\"wp-block-heading\">Stellenbeschreibung:<\/h5>\n\n<p class=\"wp-block-paragraph\">Als ServiceNow Certified Master Architect bei Fortuna leiten Sie das Design und die Implementierung von ServiceNow-L\u00f6sungen f\u00fcr Kunden. Sie arbeiten eng mit den Beteiligten zusammen, um Anforderungen zu erfassen, L\u00f6sungen zu entwerfen und den Entwicklungs- und Implementierungsprozess zu \u00fcberwachen. Diese Rolle erfordert ein tiefes Verst\u00e4ndnis der ServiceNow-Plattform und die F\u00e4higkeit, Gesch\u00e4ftsanforderungen effektiv in technische L\u00f6sungen umzusetzen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Job-Anforderungen: Stellenbeschreibung: Als ServiceNow Certified Master Architect bei Fortuna leiten Sie das Design und die Implementierung von ServiceNow-L\u00f6sungen f\u00fcr Kunden. Sie arbeiten eng mit den Beteiligten zusammen, um Anforderungen zu erfassen, L\u00f6sungen zu entwerfen und den Entwicklungs- und Implementierungsprozess zu \u00fcberwachen. Diese Rolle erfordert ein tiefes Verst\u00e4ndnis der ServiceNow-Plattform und die F\u00e4higkeit, Gesch\u00e4ftsanforderungen effektiv in [&hellip;]<\/p>\n","protected":false},"featured_media":1066,"template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"class_list":["post-1476","job-openings","type-job-openings","status-publish","has-post-thumbnail","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Job-Anforderungen: ServiceNow Certified Master Architect Zertifizierung. Umfassende Erfahrung mit der Implementierung der ServiceNow-Plattform und dem Entwurf der Architektur. Starke Probleml\u00f6sungs- und analytische F\u00e4higkeiten. Die F\u00e4higkeit, j\u00fcngere Teammitglieder zu f\u00fchren und zu betreuen. Stellenbeschreibung: Als ServiceNow Certified Master Architect bei Fortuna leiten Sie das Design und die Implementierung von ServiceNow-L\u00f6sungen f\u00fcr Kunden. Sie arbeiten eng mit\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"google-site-verification\" content=\"P42_a3YGmgYpAraZblCxsV7vHjosytTlEacnUXUnxXs\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/just-faster.com\/de\/archive-job-openings\/servicenow-zertifizierter-master-architekt-fortuna\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Just-Faster Group | Elevate your business with Just-Faster Group \u2013 a leading provider of innovative solutions and strategic consulting services. Discover how our expertise and commitment to excellence can drive your organization forward.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"ServiceNow Zertifizierter Master Architekt (Fortuna) | Just-Faster Group\" \/>\n\t\t<meta property=\"og:description\" content=\"Job-Anforderungen: ServiceNow Certified Master Architect Zertifizierung. Umfassende Erfahrung mit der Implementierung der ServiceNow-Plattform und dem Entwurf der Architektur. Starke Probleml\u00f6sungs- und analytische F\u00e4higkeiten. Die F\u00e4higkeit, j\u00fcngere Teammitglieder zu f\u00fchren und zu betreuen. Stellenbeschreibung: Als ServiceNow Certified Master Architect bei Fortuna leiten Sie das Design und die Implementierung von ServiceNow-L\u00f6sungen f\u00fcr Kunden. Sie arbeiten eng mit\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/just-faster.com\/de\/archive-job-openings\/servicenow-zertifizierter-master-architekt-fortuna\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/justfaster.qpes.com\/wp-content\/uploads\/2024\/05\/icon-just-faster.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/justfaster.qpes.com\/wp-content\/uploads\/2024\/05\/icon-just-faster.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-05-09T14:12:14+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-06-07T10:44:58+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"ServiceNow Zertifizierter Master Architekt (Fortuna) | Just-Faster Group\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Job-Anforderungen: ServiceNow Certified Master Architect Zertifizierung. Umfassende Erfahrung mit der Implementierung der ServiceNow-Plattform und dem Entwurf der Architektur. Starke Probleml\u00f6sungs- und analytische F\u00e4higkeiten. Die F\u00e4higkeit, j\u00fcngere Teammitglieder zu f\u00fchren und zu betreuen. Stellenbeschreibung: Als ServiceNow Certified Master Architect bei Fortuna leiten Sie das Design und die Implementierung von ServiceNow-L\u00f6sungen f\u00fcr Kunden. Sie arbeiten eng mit\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/justfaster.qpes.com\/wp-content\/uploads\/2024\/05\/icon-just-faster.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/just-faster.com\\\/de\\\/archive-job-openings\\\/servicenow-zertifizierter-master-architekt-fortuna\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/just-faster.com\\\/de\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/just-faster.com\\\/de\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/just-faster.com\\\/de\\\/archive-job-openings\\\/#listItem\",\"name\":\"Careers\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/just-faster.com\\\/de\\\/archive-job-openings\\\/#listItem\",\"position\":2,\"name\":\"Careers\",\"item\":\"https:\\\/\\\/just-faster.com\\\/de\\\/archive-job-openings\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/just-faster.com\\\/de\\\/archive-job-openings\\\/servicenow-zertifizierter-master-architekt-fortuna\\\/#listItem\",\"name\":\"ServiceNow Zertifizierter Master Architekt (Fortuna)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/just-faster.com\\\/de\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/just-faster.com\\\/de\\\/archive-job-openings\\\/servicenow-zertifizierter-master-architekt-fortuna\\\/#listItem\",\"position\":3,\"name\":\"ServiceNow Zertifizierter Master Architekt (Fortuna)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/just-faster.com\\\/de\\\/archive-job-openings\\\/#listItem\",\"name\":\"Careers\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/just-faster.com\\\/de\\\/#organization\",\"name\":\"Just-Faster Group\",\"description\":\"Elevate your business with Just-Faster Group \\u2013 a leading provider of innovative solutions and strategic consulting services. Discover how our expertise and commitment to excellence can drive your organization forward.\",\"url\":\"https:\\\/\\\/just-faster.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/justfaster.qpes.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/icon-just-faster.png\",\"@id\":\"https:\\\/\\\/just-faster.com\\\/de\\\/archive-job-openings\\\/servicenow-zertifizierter-master-architekt-fortuna\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/just-faster.com\\\/de\\\/archive-job-openings\\\/servicenow-zertifizierter-master-architekt-fortuna\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/just-faster-ag\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/just-faster.com\\\/de\\\/archive-job-openings\\\/servicenow-zertifizierter-master-architekt-fortuna\\\/#webpage\",\"url\":\"https:\\\/\\\/just-faster.com\\\/de\\\/archive-job-openings\\\/servicenow-zertifizierter-master-architekt-fortuna\\\/\",\"name\":\"ServiceNow Zertifizierter Master Architekt (Fortuna) | Just-Faster Group\",\"description\":\"Job-Anforderungen: ServiceNow Certified Master Architect Zertifizierung. Umfassende Erfahrung mit der Implementierung der ServiceNow-Plattform und dem Entwurf der Architektur. Starke Probleml\\u00f6sungs- und analytische F\\u00e4higkeiten. Die F\\u00e4higkeit, j\\u00fcngere Teammitglieder zu f\\u00fchren und zu betreuen. Stellenbeschreibung: Als ServiceNow Certified Master Architect bei Fortuna leiten Sie das Design und die Implementierung von ServiceNow-L\\u00f6sungen f\\u00fcr Kunden. Sie arbeiten eng mit\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/just-faster.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/just-faster.com\\\/de\\\/archive-job-openings\\\/servicenow-zertifizierter-master-architekt-fortuna\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/just-faster.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/ServiceNow-Certified-Master-Architect-Fortuna.jpg\",\"@id\":\"https:\\\/\\\/just-faster.com\\\/de\\\/archive-job-openings\\\/servicenow-zertifizierter-master-architekt-fortuna\\\/#mainImage\",\"width\":960,\"height\":640},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/just-faster.com\\\/de\\\/archive-job-openings\\\/servicenow-zertifizierter-master-architekt-fortuna\\\/#mainImage\"},\"datePublished\":\"2024-05-09T14:12:14+00:00\",\"dateModified\":\"2024-06-07T10:44:58+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/just-faster.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/just-faster.com\\\/de\\\/\",\"name\":\"Just-Faster Group\",\"alternateName\":\"Just-Faster\",\"description\":\"Elevate your business with Just-Faster Group \\u2013 a leading provider of innovative solutions and strategic consulting services. Discover how our expertise and commitment to excellence can drive your organization forward.\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/just-faster.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"ServiceNow Zertifizierter Master Architekt (Fortuna) | Just-Faster Group","description":"Job-Anforderungen: ServiceNow Certified Master Architect Zertifizierung. Umfassende Erfahrung mit der Implementierung der ServiceNow-Plattform und dem Entwurf der Architektur. Starke Probleml\u00f6sungs- und analytische F\u00e4higkeiten. Die F\u00e4higkeit, j\u00fcngere Teammitglieder zu f\u00fchren und zu betreuen. Stellenbeschreibung: Als ServiceNow Certified Master Architect bei Fortuna leiten Sie das Design und die Implementierung von ServiceNow-L\u00f6sungen f\u00fcr Kunden. Sie arbeiten eng mit","canonical_url":"https:\/\/just-faster.com\/de\/archive-job-openings\/servicenow-zertifizierter-master-architekt-fortuna\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"P42_a3YGmgYpAraZblCxsV7vHjosytTlEacnUXUnxXs","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/just-faster.com\/de\/archive-job-openings\/servicenow-zertifizierter-master-architekt-fortuna\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/just-faster.com\/de\/#listItem","position":1,"name":"Home","item":"https:\/\/just-faster.com\/de\/","nextItem":{"@type":"ListItem","@id":"https:\/\/just-faster.com\/de\/archive-job-openings\/#listItem","name":"Careers"}},{"@type":"ListItem","@id":"https:\/\/just-faster.com\/de\/archive-job-openings\/#listItem","position":2,"name":"Careers","item":"https:\/\/just-faster.com\/de\/archive-job-openings\/","nextItem":{"@type":"ListItem","@id":"https:\/\/just-faster.com\/de\/archive-job-openings\/servicenow-zertifizierter-master-architekt-fortuna\/#listItem","name":"ServiceNow Zertifizierter Master Architekt (Fortuna)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/just-faster.com\/de\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/just-faster.com\/de\/archive-job-openings\/servicenow-zertifizierter-master-architekt-fortuna\/#listItem","position":3,"name":"ServiceNow Zertifizierter Master Architekt (Fortuna)","previousItem":{"@type":"ListItem","@id":"https:\/\/just-faster.com\/de\/archive-job-openings\/#listItem","name":"Careers"}}]},{"@type":"Organization","@id":"https:\/\/just-faster.com\/de\/#organization","name":"Just-Faster Group","description":"Elevate your business with Just-Faster Group \u2013 a leading provider of innovative solutions and strategic consulting services. Discover how our expertise and commitment to excellence can drive your organization forward.","url":"https:\/\/just-faster.com\/de\/","logo":{"@type":"ImageObject","url":"https:\/\/justfaster.qpes.com\/wp-content\/uploads\/2024\/05\/icon-just-faster.png","@id":"https:\/\/just-faster.com\/de\/archive-job-openings\/servicenow-zertifizierter-master-architekt-fortuna\/#organizationLogo"},"image":{"@id":"https:\/\/just-faster.com\/de\/archive-job-openings\/servicenow-zertifizierter-master-architekt-fortuna\/#organizationLogo"},"sameAs":["https:\/\/www.linkedin.com\/company\/just-faster-ag\/"]},{"@type":"WebPage","@id":"https:\/\/just-faster.com\/de\/archive-job-openings\/servicenow-zertifizierter-master-architekt-fortuna\/#webpage","url":"https:\/\/just-faster.com\/de\/archive-job-openings\/servicenow-zertifizierter-master-architekt-fortuna\/","name":"ServiceNow Zertifizierter Master Architekt (Fortuna) | Just-Faster Group","description":"Job-Anforderungen: ServiceNow Certified Master Architect Zertifizierung. Umfassende Erfahrung mit der Implementierung der ServiceNow-Plattform und dem Entwurf der Architektur. Starke Probleml\u00f6sungs- und analytische F\u00e4higkeiten. Die F\u00e4higkeit, j\u00fcngere Teammitglieder zu f\u00fchren und zu betreuen. Stellenbeschreibung: Als ServiceNow Certified Master Architect bei Fortuna leiten Sie das Design und die Implementierung von ServiceNow-L\u00f6sungen f\u00fcr Kunden. Sie arbeiten eng mit","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/just-faster.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/just-faster.com\/de\/archive-job-openings\/servicenow-zertifizierter-master-architekt-fortuna\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/just-faster.com\/wp-content\/uploads\/2024\/05\/ServiceNow-Certified-Master-Architect-Fortuna.jpg","@id":"https:\/\/just-faster.com\/de\/archive-job-openings\/servicenow-zertifizierter-master-architekt-fortuna\/#mainImage","width":960,"height":640},"primaryImageOfPage":{"@id":"https:\/\/just-faster.com\/de\/archive-job-openings\/servicenow-zertifizierter-master-architekt-fortuna\/#mainImage"},"datePublished":"2024-05-09T14:12:14+00:00","dateModified":"2024-06-07T10:44:58+00:00"},{"@type":"WebSite","@id":"https:\/\/just-faster.com\/de\/#website","url":"https:\/\/just-faster.com\/de\/","name":"Just-Faster Group","alternateName":"Just-Faster","description":"Elevate your business with Just-Faster Group \u2013 a leading provider of innovative solutions and strategic consulting services. Discover how our expertise and commitment to excellence can drive your organization forward.","inLanguage":"de-DE","publisher":{"@id":"https:\/\/just-faster.com\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Just-Faster Group | Elevate your business with Just-Faster Group \u2013 a leading provider of innovative solutions and strategic consulting services. Discover how our expertise and commitment to excellence can drive your organization forward.","og:type":"article","og:title":"ServiceNow Zertifizierter Master Architekt (Fortuna) | Just-Faster Group","og:description":"Job-Anforderungen: ServiceNow Certified Master Architect Zertifizierung. Umfassende Erfahrung mit der Implementierung der ServiceNow-Plattform und dem Entwurf der Architektur. Starke Probleml\u00f6sungs- und analytische F\u00e4higkeiten. Die F\u00e4higkeit, j\u00fcngere Teammitglieder zu f\u00fchren und zu betreuen. Stellenbeschreibung: Als ServiceNow Certified Master Architect bei Fortuna leiten Sie das Design und die Implementierung von ServiceNow-L\u00f6sungen f\u00fcr Kunden. Sie arbeiten eng mit","og:url":"https:\/\/just-faster.com\/de\/archive-job-openings\/servicenow-zertifizierter-master-architekt-fortuna\/","og:image":"https:\/\/justfaster.qpes.com\/wp-content\/uploads\/2024\/05\/icon-just-faster.png","og:image:secure_url":"https:\/\/justfaster.qpes.com\/wp-content\/uploads\/2024\/05\/icon-just-faster.png","article:published_time":"2024-05-09T14:12:14+00:00","article:modified_time":"2024-06-07T10:44:58+00:00","twitter:card":"summary_large_image","twitter:title":"ServiceNow Zertifizierter Master Architekt (Fortuna) | Just-Faster Group","twitter:description":"Job-Anforderungen: ServiceNow Certified Master Architect Zertifizierung. Umfassende Erfahrung mit der Implementierung der ServiceNow-Plattform und dem Entwurf der Architektur. Starke Probleml\u00f6sungs- und analytische F\u00e4higkeiten. Die F\u00e4higkeit, j\u00fcngere Teammitglieder zu f\u00fchren und zu betreuen. Stellenbeschreibung: Als ServiceNow Certified Master Architect bei Fortuna leiten Sie das Design und die Implementierung von ServiceNow-L\u00f6sungen f\u00fcr Kunden. Sie arbeiten eng mit","twitter:image":"https:\/\/justfaster.qpes.com\/wp-content\/uploads\/2024\/05\/icon-just-faster.png"},"aioseo_meta_data":{"post_id":"1476","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2024-06-07 10:44:57","updated":"2025-06-05 00:02:18","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/just-faster.com\/de\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/just-faster.com\/de\/archive-job-openings\/\" title=\"Careers\">Careers<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tServiceNow Zertifizierter Master Architekt (Fortuna)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/just-faster.com\/de\/"},{"label":"Careers","link":"https:\/\/just-faster.com\/de\/archive-job-openings\/"},{"label":"ServiceNow Zertifizierter Master Architekt (Fortuna)","link":"https:\/\/just-faster.com\/de\/archive-job-openings\/servicenow-zertifizierter-master-architekt-fortuna\/"}],"_links":{"self":[{"href":"https:\/\/just-faster.com\/de\/wp-json\/wp\/v2\/job-openings\/1476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/just-faster.com\/de\/wp-json\/wp\/v2\/job-openings"}],"about":[{"href":"https:\/\/just-faster.com\/de\/wp-json\/wp\/v2\/types\/job-openings"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/just-faster.com\/de\/wp-json\/wp\/v2\/media\/1066"}],"wp:attachment":[{"href":"https:\/\/just-faster.com\/de\/wp-json\/wp\/v2\/media?parent=1476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}